{"id":8089,"date":"2021-12-20T18:52:08","date_gmt":"2021-12-20T17:52:08","guid":{"rendered":"https:\/\/www.sorainstyles.com\/boutique\/produit\/blackened-2011-sp\/"},"modified":"2024-05-03T12:27:21","modified_gmt":"2024-05-03T10:27:21","slug":"blackened-2011-sp","status":"publish","type":"product","link":"https:\/\/www.sorainstyles.com\/boutique\/produit\/blackened-2011-sp\/","title":{"rendered":"Blackened 2011 \u00c9chantillon"},"content":{"rendered":"<h2>Un blanc frais<\/h2>\n<div class=\"ui-textMD2\">\n<p>L\u2019\u00e9chantillon <a href=\"https:\/\/www.sorainstyles.com\/boutique\/produit\/blackened-2011\/\" target=\"_blank\" rel=\"noopener\">No.2011 Blackened<\/a>\u00a0est un blanc frais qui poss\u00e8de une touche tr\u00e8s l\u00e9g\u00e8re de <a href=\"https:\/\/www.cotemaison.fr\/couleurs\/couleur-gris-peinture-gris-clair-gris-anthracite_11682.html\" target=\"_blank\" rel=\"noopener\">gris<\/a>. Historiquement, elle \u00e9tait fabriqu\u00e9e en y ajoutant du noir de fum\u00e9e, un pigment fabriqu\u00e9 \u00e0 base de r\u00e9sidus d\u2019huile de lampe \u00e0 br\u00fbler.<\/p>\n<p><u>Attention, l\u2019\u00e9chantillon Blackened No.2011 n\u2019est disponible uniquement en finition Estate Emulsion\u00a0au format 100 ml.<\/u><\/p>\n<h4>Pourquoi utiliser les pots \u00e9chantillons Farrow &amp; Ball ?<\/h4>\n<p>Tout simplement car c\u2019est la meilleure mani\u00e8re de tester les couleurs avant de vous lancer. Cela vous permet de voir la teinte r\u00e9elle in situ.<\/p>\n<p>Deuxi\u00e8mement, les pots d\u2019\u00e9chantillons vous aide \u00e0 limiter votre pr\u00e9s\u00e9lection de teintes. Ils vous permettent ensuite de confirmer ou non une teinte que vous auriez vu sur le nuancier.<\/p>\n<p><u>NB : les pots d\u2019\u00e9chantillons sont disponibles uniquement pour toutes les couleurs du nuancier actuel de Farrow &amp; Ball.<\/u><\/p>\n<h4>Comment utiliser les pots \u00e9chantillons Farrow &amp; Ball ?<\/h4>\n<h5>1. Peignez<\/h5>\n<p>Plut\u00f4t que d\u2019appliquer la peinture directement sur le mur, nous vous recommandons de passer deux couches de chacun de vos \u00e9chantillons de peinture sur des feuilles de papier ou de carton et de les laisser s\u00e9cher.<\/p>\n<h5>2. Positionnez<\/h5>\n<p>Placez vos feuilles dans la pi\u00e8ce que vous pr\u00e9voyez de peindre. D\u00e9placez-les \u00e0 diff\u00e9rents endroits de la pi\u00e8ce pour voir comment la couleur \u00e9volue au cours de la journ\u00e9e et selon le type de lumi\u00e8re.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Un blanc frais L\u2019\u00e9chantillon No.2011 Blackened\u00a0est un blanc frais qui poss\u00e8de une touche tr\u00e8s l\u00e9g\u00e8re de gris. Historiquement, elle \u00e9tait fabriqu\u00e9e en y ajoutant du noir de fum\u00e9e, un pigment fabriqu\u00e9 \u00e0 base de r\u00e9sidus d\u2019huile de lampe \u00e0 br\u00fbler. Attention, l\u2019\u00e9chantillon Blackened No.2011 n\u2019est disponible uniquement en finition Estate Emulsion\u00a0au format 100 ml. Pourquoi [&hellip;]<\/p>\n","protected":false},"featured_media":7774,"template":"","meta":{"_acf_changed":false,"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":""},"product_brand":[],"product_cat":[349],"product_tag":[],"class_list":{"0":"post-8089","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-pots-echantillons","8":"first","9":"instock","10":"taxable","11":"shipping-taxable","12":"purchasable","13":"product-type-variable"},"acf":[],"_links":{"self":[{"href":"https:\/\/www.sorainstyles.com\/boutique\/wp-json\/wp\/v2\/product\/8089","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sorainstyles.com\/boutique\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.sorainstyles.com\/boutique\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.sorainstyles.com\/boutique\/wp-json\/wp\/v2\/media\/7774"}],"wp:attachment":[{"href":"https:\/\/www.sorainstyles.com\/boutique\/wp-json\/wp\/v2\/media?parent=8089"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.sorainstyles.com\/boutique\/wp-json\/wp\/v2\/product_brand?post=8089"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.sorainstyles.com\/boutique\/wp-json\/wp\/v2\/product_cat?post=8089"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.sorainstyles.com\/boutique\/wp-json\/wp\/v2\/product_tag?post=8089"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}